{"id":3,"date":"2019-09-20T10:48:01","date_gmt":"2019-09-20T08:48:01","guid":{"rendered":"https:\/\/www.sternchemie.com\/?page_id=3"},"modified":"2026-03-30T16:18:39","modified_gmt":"2026-03-30T14:18:39","slug":"datenschutz","status":"publish","type":"page","link":"https:\/\/www.sternchemie.com\/de\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"<div  class=\"tatsu-gg9fxvdqw0fk6qd1 tatsu-section  tatsu-bg-overlay   tatsu-clearfix\" data-title=\"\"  data-headerscheme=\"background--dark\"><div class='tatsu-section-pad clearfix' data-padding='{\"d\":\"90px 0px 90px 0px\"}' data-padding-top='90px'><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-TUovk9O9Q4\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-bg-overlay tatsu-one-col tatsu-column-image-none tatsu-column-effect-none  tatsu-BESRNEKfm\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"tatsu-module tatsu-inline-text clearfix tatsu-Uk7UtkQ87   \" ><style>.tatsu-Uk7UtkQ87 .tatsu-inline-text-inner{width: 100%;text-align: left;}@media only screen and (max-width: 767px) {.tatsu-Uk7UtkQ87 .tatsu-inline-text-inner{width: 100%;}}<\/style><div class=\"tatsu-inline-text-inner tatsu-align-center\">\n<h1>Datenschutzerkl\u00e4rung<\/h1>\n<\/div><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-column-overlay tatsu-animate-none\" ><\/div><\/div><style>.tatsu-row > .tatsu-BESRNEKfm.tatsu-column{width: 100%;}.tatsu-BESRNEKfm.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: normal;}.tatsu-BESRNEKfm > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-BESRNEKfm > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-BESRNEKfm > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-BESRNEKfm > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}@media only screen and (max-width:1377px) {.tatsu-row > .tatsu-BESRNEKfm.tatsu-column{width: 100%;}}@media only screen and (min-width:768px) and (max-width: 1024px) {.tatsu-row > .tatsu-BESRNEKfm.tatsu-column{width: 100%;}}@media only screen and (max-width: 767px) {.tatsu-row > .tatsu-BESRNEKfm.tatsu-column{width: 100%;}}<\/style><\/div><\/div><\/div><div class=\"tatsu-row-wrap  tatsu-wrap tatsu-row-one-col tatsu-row-has-one-cols tatsu-medium-gutter tatsu-reg-cols  tatsu-clearfix tatsu-gg9fxvdqyb58q79a\" ><div  class=\"tatsu-row \" ><div  class=\"tatsu-column  tatsu-bg-overlay tatsu-one-col tatsu-column-image-none tatsu-column-effect-none  tatsu-gg9fxvdr0t9rudhd\"  data-parallax-speed=\"0\" style=\"\"><div class=\"tatsu-column-inner \" ><div class=\"tatsu-column-pad-wrap\"><div class=\"tatsu-column-pad\" ><div  class=\"tatsu-module tatsu-inline-text clearfix tatsu-FOU2KdtX-   \" ><style>.tatsu-FOU2KdtX- .tatsu-inline-text-inner{width: 100%;text-align: left;}.tatsu-FOU2KdtX-.tatsu-inline-text .tatsu-inline-text-inner *{}@media only screen and (max-width: 767px) {.tatsu-FOU2KdtX- .tatsu-inline-text-inner{width: 100%;}}<\/style><div class=\"tatsu-inline-text-inner tatsu-align-center\">\n<p><strong>1. Name und Kontaktdaten des f\u00fcr die Verarbeitung Verantwortlichen sowie des betrieblichen Datenschutzbeauftragten<\/strong><\/p>\n<p>Diese Datenschutz-Information gilt f\u00fcr die Datenverarbeitung durch:<\/p>\n<p>Verantwortlicher:<br \/>Sternchemie GmbH & Co. KG,<br \/>An der Alster 81, 20099 Hamburg, Germany<br \/>Email: <a href=\"data@sternchemie.de\" target=\"_blank\" rel=\"noopener\">data@sternchemie.de<\/a><br \/>Telefon: +49 (0)40 \u2013 284 09 58 \u2013 10<br \/>Fax: +49 (0)40 \u2013 284 039 \u2013 76<\/p>\n<p>Der betriebliche Datenschutzbeauftragte ist \u00fcber die o.g. Anschrift, zu Hd. Herrn Sven Naucke, beziehungsweise unter data@sternchemie.de erreichbar.<\/p>\n<p><strong>2. Erhebung und Speicherung personenbezogener Daten sowie Art und Zweck von deren Verwendung<\/strong><\/p>\n<p>a) Beim Besuch der Website<\/p>\n<p>Beim Aufrufen unserer Website <a href=\"www.sternchemie.com\/de\/\" target=\"_blank\" rel=\"noopener\">www.sternchemie.com\/de\/<\/a> werden durch den auf Ihrem Endger\u00e4t zum Einsatz kommenden Browser automatisch Informationen an den Server unserer Website gesendet. Diese Informationen werden tempor\u00e4r in einem sog. Logfile gespeichert. Folgende Informationen werden dabei ohne Ihr Zutun erfasst und bis zur automatisierten L\u00f6schung gespeichert:<\/p>\n<ul>\n<li>IP-Adresse des anfragenden Rechners,<\/li>\n<li>Datum und Uhrzeit des Zugriffs,<\/li>\n<li>Name und URL der abgerufenen Datei,<\/li>\n<li>Website, von der aus der Zugriff erfolgt (Referrer-URL),<\/li>\n<li>verwendeter Browser und ggf. das Betriebssystem Ihres Rechners sowie der Name Ihres Access-Providers.<\/li>\n<\/ul>\n<p>Die genannten Daten werden durch uns zu folgenden Zwecken verarbeitet:<\/p>\n<ul>\n<li>Gew\u00e4hrleistung eines reibungslosen Verbindungsaufbaus der Website,<\/li>\n<li>Gew\u00e4hrleistung einer komfortablen Nutzung unserer Website,<\/li>\n<li>Auswertung der Systemsicherheit und -stabilit\u00e4t sowie<\/li>\n<li>zu weiteren administrativen Zwecken.<\/li>\n<\/ul>\n<p>Die Rechtsgrundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 S. 1 lit. f DSGVO. Unser berechtigtes Interesse folgt aus oben aufgelisteten Zwecken zur Datenerhebung. In keinem Fall verwenden wir die erhobenen Daten zu dem Zweck, R\u00fcckschl\u00fcsse auf Ihre Person zu ziehen.<\/p>\n<p>Dar\u00fcber hinaus setzen wir beim Besuch unserer Website Cookies sowie Analysedienste ein. N\u00e4here Erl\u00e4uterungen dazu erhalten Sie unter den Ziff. 4 und 5 dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>b) Bei Anmeldung f\u00fcr unseren Newsletter<\/p>\n<p>Sofern Sie nach Art. 6 Abs. 1 S. 1 lit. a DSGVO ausdr\u00fccklich eingewilligt haben, verwenden wir Ihre E-Mail-Adresse daf\u00fcr, Ihnen regelm\u00e4\u00dfig unseren Newsletter zu \u00fcbersenden. F\u00fcr den Empfang des Newsletters ist die Angabe einer E-Mail-Adresse ausreichend.<\/p>\n<p>Die Abmeldung ist jederzeit m\u00f6glich, zum Beispiel \u00fcber einen Link am Ende eines jeden Newsletters. Alternativ k\u00f6nnen Sie Ihren Abmeldewunsch gerne auch jederzeit an <a href=\"data@sternchemie.de\" target=\"_blank\" rel=\"noopener\">data@sternchemie.de<\/a> per E-Mail senden.<\/p>\n<p>c) Bei Nutzung unseres Kontaktformulars<\/p>\n<p class=\"MsoNormal\">Bei Fragen jeglicher Art bieten wir Ihnen die M\u00f6glichkeit, mit uns \u00fcber ein auf der Website bereitgestelltes Formular Kontakt aufzunehmen. Dabei erfassen wir Ihren Namen, Ihre E-Mailadresse und Firmennamen und Ihre Telefonnummer, um Ihre Anfrage bearbeiten zu k\u00f6nnen. Weitere Angaben k\u00f6nnen freiwillig get\u00e4tigt werden.<\/p>\n<p class=\"MsoNormal\">Die Datenverarbeitung zum Zwecke der Kontaktaufnahme mit uns erfolgt nach Art. 6 Abs. 1 S. 1 lit. a DSGVO auf Grundlage Ihrer freiwillig erteilten Einwilligung.<\/p>\n<p>\u00a0<\/p>\n<p class=\"MsoNormal\">Die f\u00fcr die Benutzung des Kontaktformulars von uns erhobenen personenbezogenen Daten werden nach Erledigung der von Ihnen gestellten Anfrage sp\u00e4testens aber nach 1 Jahr gel\u00f6scht.<\/p>\n<p>\u00a0<\/p>\n<p><strong>3. Weitergabe von Daten<\/strong><\/p>\n<p>Eine \u00dcbermittlung Ihrer pers\u00f6nlichen Daten an Dritte zu anderen als den im Folgenden aufgef\u00fchrten Zwecken findet nicht statt. Wir geben Ihre pers\u00f6nlichen Daten nur an Dritte weiter, wenn:<\/p>\n<ul>\n<li>Sie Ihre nach Art. 6 Abs. 1 S. 1 lit. a DSGVO ausdr\u00fcckliche Einwilligung dazu erteilt haben,<\/li>\n<li><span style=\"font-size: 17px; letter-spacing: 0px;\">die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. f DSGVO zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe Ihrer Daten haben,<\/span><\/li>\n<li>f\u00fcr den Fall, dass f\u00fcr die Weitergabe nach Art. 6 Abs. 1 S. 1 lit. c DSGVO eine gesetzliche Verpflichtung besteht, sowie<\/li>\n<li>dies gesetzlich zul\u00e4ssig und nach Art. 6 Abs. 1 S. 1 lit. b DSGVO f\u00fcr die Abwicklung von Vertragsverh\u00e4ltnissen mit Ihnen erforderlich ist.<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<p><strong>4. Cookies<\/strong><\/p>\n<p>Wir setzen auf unserer Seite Cookies ein. Hierbei handelt es sich um kleine Dateien, die Ihr Browser automatisch erstellt und die auf Ihrem Endger\u00e4t (Laptop, Tablet, Smartphone o.\u00e4.) gespeichert werden, wenn Sie unsere Seite besuchen. Cookies richten auf Ihrem Endger\u00e4t keinen Schaden an, enthalten keine Viren, Trojaner oder sonstige Schadsoftware.<\/p>\n<p>In dem Cookie werden Informationen abgelegt, die sich jeweils im Zusammenhang mit dem spezifisch eingesetzten Endger\u00e4t ergeben. Dies bedeutet jedoch nicht, dass wir dadurch unmittelbar Kenntnis von Ihrer Identit\u00e4t erhalten.<\/p>\n<p>Der Einsatz von Cookies dient einerseits dazu, die Nutzung unseres Angebots f\u00fcr Sie angenehmer zu gestalten. So setzen wir sogenannte Session-Cookies ein, um zu erkennen, dass Sie einzelne Seiten unserer Website bereits besucht haben. Diese werden nach Verlassen unserer Seite automatisch gel\u00f6scht.<\/p>\n<p>Dar\u00fcber hinaus setzen wir ebenfalls zur Optimierung der Benutzerfreundlichkeit tempor\u00e4re Cookies ein, die f\u00fcr einen bestimmten festgelegten Zeitraum auf Ihrem Endger\u00e4t gespeichert werden. Besuchen Sie unsere Seite erneut, um unsere Dienste in Anspruch zu nehmen, wird automatisch erkannt, dass Sie bereits bei uns waren und welche Eingaben und Einstellungen sie get\u00e4tigt haben, um diese nicht noch einmal eingeben zu m\u00fcssen.<\/p>\n<p>Zum anderen setzten wir Cookies ein, um die Nutzung unserer Website statistisch zu erfassen und zum Zwecke der Optimierung unseres Angebotes f\u00fcr Sie auszuwerten (siehe Ziff. 5). Diese Cookies erm\u00f6glichen es uns, bei einem erneuten Besuch unserer Seite automatisch zu erkennen, dass Sie bereits bei uns waren. Diese Cookies werden nach einer jeweils definierten Zeit automatisch gel\u00f6scht.<\/p>\n<p>Die durch Cookies verarbeiteten Daten k\u00f6nnen dadurch zur Wahrung unserer berechtigten Interessen sowie Dritter nach Art. 6 Abs. 1 S. 1 lit. f DSGVO erforderlich sein. Dar\u00fcber hinaus k\u00f6nnen Cookies oder vergleichbare Wiedererkennungstechnologien aber auch auf Grundlage einer erteilten Einwilligung nach Art. 6 Abs. 1 S. 1 lit. a DSGVO genutzt werden; die Einwilligung ist jederzeit widerrufbar.\u00a0<\/p>\n<p>Die meisten Browser akzeptieren Cookies automatisch. Sie k\u00f6nnen Ihren Browser jedoch so konfigurieren, dass keine Cookies auf Ihrem Computer gespeichert werden oder stets ein Hinweis erscheint, bevor ein neuer Cookie angelegt wird. Die vollst\u00e4ndige Deaktivierung von Cookies kann jedoch dazu f\u00fchren, dass Sie nicht alle Funktionen unserer Website nutzen k\u00f6nnen.<\/p>\n<p>\u00a0<\/p>\n<p><strong>5. Analyse-Tools<\/strong><\/p>\n<p>Die im Folgenden aufgef\u00fchrten und von uns eingesetzten Tracking-Ma\u00dfnahmen werden auf Grundlage des Art. 6 Abs. 1 S. 1 lit. f) DSGVO oder Artikel 6 Abs. 1 lit. a) DSGVO durchgef\u00fchrt. Mit den zum Einsatz kommenden Tracking-Ma\u00dfnahmen wollen wir eine bedarfsgerechte Gestaltung und die fortlaufende Optimierung unserer Webseite sicherstellen. Zum anderen setzen wir die Tracking-Ma\u00dfnahmen ein, um die Nutzung unserer Webseite statistisch zu erfassen und zum Zwecke der Optimierung unseres Angebotes f\u00fcr Sie auszuwerten. Die Grundlagen hierf\u00fcr k\u00f6nnen berechtigtes Interesse oder eine Einwilligung sein.<\/p>\n<p>Die jeweiligen Datenverarbeitungszwecke und Datenkategorien sind aus den entsprechenden Tracking-Tools zu entnehmen.<\/p>\n<p>i) Google Analytics<\/p>\n<p>Zum Zwecke der bedarfsgerechten Gestaltung und fortlaufenden Optimierung unserer Seiten nutzen wir Google Analytics, ein Webanalysedienst der Google Inc. (<a href=\"https:\/\/www.google.de\/intl\/de\/about\/\" target=\"_self\" rel=\"noopener\">https:\/\/www.google.de\/intl\/de\/about\/<\/a>) (1600 Amphitheatre Parkway, Mountain View, CA 94043, USA; im Folgenden \u201eGoogle\u201c). In diesem Zusammenhang werden pseudonymisierte Nutzungsprofile erstellt und Cookies (siehe unter Ziff. 4) verwendet. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website wie<\/p>\n<ul>\n<li>Browser-Typ\/-Version,<\/li>\n<li>verwendetes Betriebssystem,<\/li>\n<li>Referrer-URL (die zuvor besuchte Seite),<\/li>\n<li>Hostname des zugreifenden Rechners (IP-Adresse),<\/li>\n<li>Uhrzeit der Serveranfrage,<\/li>\n<\/ul>\n<p>werden an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Die Informationen werden verwendet, um die Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen zu Zwecken der Marktforschung und bedarfsgerechten Gestaltung dieser Internetseiten zu erbringen. Auch werden diese Informationen gegebenenfalls an Dritte \u00fcbertragen, sofern dies gesetzlich vorgeschrieben ist oder soweit Dritte diese Daten im Auftrag verarbeiten. Es wird in keinem Fall Ihre IP-Adresse mit anderen Daten von Google zusammengef\u00fchrt. Die IP-Adressen werden anonymisiert, so dass eine Zuordnung nicht m\u00f6glich ist (IP-Masking).<\/p>\n<p>Die Nutzung dieses Dienstes erfolgt auf Grundlage Ihrer Einwilligung nach Art. 6 Abs. 1 lit. a DSGVO. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Sie k\u00f6nnen die Installation der Cookies durch eine entsprechende Einstellung der Browser-Software verhindern; wir weisen jedoch darauf hin, dass in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich genutzt werden k\u00f6nnen.<\/p>\n<p>Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch das Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie ein Browser-Add-on herunterladen und installieren (<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>).<\/p>\n<p>Alternativ zum Browser-Add-on, insbesondere bei Browsern auf mobilen Endger\u00e4ten, k\u00f6nnen Sie die Erfassung durch Google Analytics zudem verhindern, indem Sie auf diesen Link klicken. Es wird ein Opt-out-Cookie gesetzt, das die zuk\u00fcnftige Erfassung Ihrer Daten beim Besuch dieser Website verhindert. Der Opt-out-Cookie gilt nur in diesem Browser und nur f\u00fcr unsere Website und wird auf Ihrem Ger\u00e4t abgelegt. L\u00f6schen Sie die Cookies in diesem Browser, m\u00fcssen Sie das Opt-out-Cookie erneut setzen.<\/p>\n<p>Weitere Informationen zum Datenschutz im Zusammenhang mit Google Analytics finden Sie etwa in der Google Analytics-Hilfe (<a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>).<\/p>\n<p>b) Google Adwords Conversion Tracking<\/p>\n<p>Um die Nutzung unserer Webseite statistisch zu erfassen und zum Zwecke der Optimierung unserer Website f\u00fcr Sie auszuwerten, nutzen wir ferner das Google Conversion Tracking. Dabei wird von Google Adwords ein Cookie (siehe Ziffer 4) auf Ihrem Rechner gesetzt, sofern Sie \u00fcber eine Google-Anzeige auf unsere Webseite gelangt sind.<\/p>\n<p>Diese Cookies verlieren nach 30 Tagen ihre G\u00fcltigkeit und dienen nicht der pers\u00f6nlichen Identifizierung. Besucht der Nutzer bestimmte Seiten der Webseite des Adwords-Kunden und das Cookie ist noch nicht abgelaufen, k\u00f6nnen Google und der Kunde erkennen, dass der Nutzer auf die Anzeige geklickt hat und zu dieser Seite weitergeleitet wurde.<\/p>\n<p>Jeder Adwords-Kunde erh\u00e4lt ein anderes Cookie. Cookies k\u00f6nnen somit nicht \u00fcber die Webseiten von Adwords-Kunden nachverfolgt werden. Die mithilfe des Conversion-Cookies eingeholten Informationen dienen dazu, Conversion-Statistiken f\u00fcr Adwords-Kunden zu erstellen, die sich f\u00fcr Conversion-Tracking entschieden haben. Die Adwords-Kunden erfahren die Gesamtanzahl der Nutzer, die auf ihre Anzeige geklickt haben und zu einer mit einem Conversion-Tracking-Tag versehenen Seite weitergeleitet wurden. Sie erhalten jedoch keine Informationen, mit denen sich Nutzer pers\u00f6nlich identifizieren lassen.<\/p>\n<p>Wenn Sie nicht an dem Tracking-Verfahren teilnehmen m\u00f6chten, k\u00f6nnen Sie auch das hierf\u00fcr erforderliche Setzen eines Cookies ablehnen \u2013 etwa per Browser-Einstellung, die das automatische Setzen von Cookies generell deaktiviert. Sie k\u00f6nnen Cookies f\u00fcr Conversion-Tracking auch deaktivieren, indem Sie Ihren Browser so einstellen, dass Cookies von der Domain www.googleservices.com blockiert werden. Googles Datenschutzbelehrung zum Conversion-Tracking finden Sie hier<a href=\"https:\/\/policies.google.com\/privacy?hl=de\"> https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<p>c) Matomo<\/p>\n<p>Wir verwenden die Open-Source-Software Matomo zur Analyse und statistischen Auswertung der Nutzung der Website. Hierzu werden Cookies eingesetzt (siehe Ziffer 4). Die durch den Cookie erzeugten Informationen \u00fcber die Websitenutzung werden an unsere Server \u00fcbertragen und in pseudonymen Nutzungsprofilen zusammengefasst. Die Informationen werden verwendet, um die Nutzung der Website auszuwerten und um eine bedarfsgerechte Gestaltung unserer Website zu erm\u00f6glichen. Eine Weitergabe der Informationen an Dritte erfolgt nicht.<\/p>\n<p>Es wird in keinem Fall die IP-Adresse mit anderen den Nutzer betreffenden Daten in Verbindung gebracht. Die IP-Adressen werden anonymisiert, so dass eine Zuordnung nicht m\u00f6glich ist (IP-Masking).<\/p>\n<p>Ihr Besuch dieser Webseite wird aktuell von der Matomo Webanalyse erfasst. Klicken Sie hier (<a href=\"https:\/\/www.eff.org\/issues\/do-not-track\" target=\"_blank\" rel=\"noopener\">https:\/\/www.eff.org\/issues\/do-not-track<\/a>), damit Ihr Besuch nicht mehr erfasst wird.<\/p>\n<p>d) matelso<\/p>\n<p>Unsere Webseite benutzt einen Dienst der matelso GmbH, Stuttgart. Wenn Sie auf einer von matelso f\u00fcr uns geschalteten Rufnummer anrufen, werden Informationen zu dem Telefonat in einen von uns verwendeten Webanalysedienst (z.B. Google Analytics) \u00fcbertragen. matelso liest ferner von unserem Analysedienst gesetzte Cookies oder andere Parameter der von Ihnen besuchten Internetseite aus, zum Beispiel referrer, document path, remote user agent.<\/p>\n<p>Die entsprechenden Informationen werden gem\u00e4\u00df unseren Weisungen von matelso verarbeitet und auf Servern in der EU gespeichert. N\u00e4here Informationen finden Sie auf: <a href=\"https:\/\/matelso.com\/de\/privacy-statement\" target=\"_blank\" rel=\"noopener\">https:\/\/matelso.com\/de\/privacy-statement<\/a>. Sie k\u00f6nnen die Speicherung von Cookies durch eine entsprechende Einstellung Ihrer Browsersoftware verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall ggf. nicht s\u00e4mtliche Funktionen dieser Webseite vollumf\u00e4nglich werden nutzen k\u00f6nnen.<\/p>\n<p>e) Verwendung von Google Maps<\/p>\n<p>Im Kontaktbereich unseres Internetauftritts haben Sie die M\u00f6glichkeit den Dienst \u201cGoogle Maps\u201d des Anbieters Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, aufzurufen. Die Nutzung des Links erfolgt freiwillig. Zu den verarbeiteten Daten durch Google k\u00f6nnen insbesondere IP-Adressen und Standortdaten der Nutzer geh\u00f6ren. Die Daten k\u00f6nnen in den USA verarbeitet werden. Die Nutzung von Google Maps erfolgt im Interesse des Besuchers um den Standort besser zu finden. Rechtsgrundlagen sind erteilte Einwilligungen nach Art. 6 Abs. 1 lit. a DSGVO bzw. berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO. Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n<p>f) Amazon Cloudfront<\/p>\n<p>Wir nutzen das Content Delivery Network (CDN) Amazon CloudFront von Amazon Web Services EMEA SARL, 38 avenue John F. Kennedy, L-1855 Luxembourg (AWS), um die Sicherheit und die Auslieferungsgeschwindigkeit unserer Website zu erh\u00f6hen. Dies entspricht unserem berechtigten Interesse (Art. 6 Abs. 1 lit. f DSGVO). Ein CDN ist ein Netzwerk aus verteilten Servern, das in der Lage ist, optimiert Inhalte an den Websitenutzer auszuliefern. F\u00fcr diesen Zweck k\u00f6nnen personenbezogene Daten in Server-Logfiles von AWS verarbeitet werden. Wir bewahren Logfiles auf, um die Stabilit\u00e4t und Sicherheit unserer Website zu gew\u00e4hrleisten.<\/p>\n<p>AWS ist Empf\u00e4nger Ihrer personenbezogenen Daten und als Auftragsverarbeiter f\u00fcr uns t\u00e4tig. Der Einsatz kann auf Basis einer erteilten Einwilligung nach (Art. 6 Abs. 1 lit. a DSGVO) oder auf Grundlage eines berechtigten Interesse an einer m\u00f6glichst fehlerfreien und sicheren Bereitstellung unseres Webangebotes (Art. 6 Abs. 1 lit. f DSGVO) erfolgen.<\/p>\n<p>Sie haben das Recht der Verarbeitung zu widersprechen. Ob der Widerspruch erfolgreich ist, ist im Rahmen einer Interessenabw\u00e4gung zu ermitteln.<\/p>\n<p>Die Verarbeitung der unter diesem Abschnitt angegebenen Daten ist weder gesetzlich noch vertraglich vorgeschrieben. Die Funktionsf\u00e4higkeit der Website ist ohne die Verarbeitung nicht gew\u00e4hrleistet.<\/p>\n<p>Ihre personenbezogenen Daten werden von AWS so lange gespeichert, wie es f\u00fcr die beschriebenen Zwecke erforderlich ist.\u00a0<\/p>\n<p>Weitere Informationen zu Widerspruchs- und Beseitigungsm\u00f6glichkeiten gegen\u00fcber AWS finden Sie unter: <a href=\"https:\/\/d1.awsstatic.com\/legal\/privacypolicy\/AWS_Privacy_Notice__German_Translation.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/d1.awsstatic.com\/legal\/privacypolicy\/AWS_Privacy_Notice__German_Translation.pdf<\/a><\/p>\n<p>AWS hat Compliance-Ma\u00dfnahmen f\u00fcr internationale Daten\u00fcbermittlungen umgesetzt. Diese gelten f\u00fcr alle weltweiten Aktivit\u00e4ten, bei denen AWS personenbezogene Daten von nat\u00fcrlichen Personen in der EU verarbeitet. Diese Ma\u00dfnahmen basieren auf den EU-Standardvertragsklauseln (SCCs). Weitere Informationen finden Sie unter: <a href=\"https:\/\/d1.awsstatic.com\/legal\/aws-gdpr\/AWS_GDPR_DPA.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/d1.awsstatic.com\/legal\/aws-gdpr\/AWS_GDPR_DPA.pdf<\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong>6. SOCIAL MEDIA PLUG-INS<\/strong><\/p>\n<p>Wir setzen auf unserer Website auf Grundlage des Art. 6 Abs. 1 S. 1 lit. f Social Plug-ins der sozialen Netzwerke LinkedIn und Xing ein, um unser Unternehmen hier\u00fcber bekannter zu machen. Der dahinterstehende werbliche Zweck ist als berechtigtes Interesse im Sinne der DSGVO anzusehen. Die Verantwortung f\u00fcr den datenschutzkonformen Betrieb ist durch deren jeweiligen Anbieter zu gew\u00e4hrleisten. Die Einbindung dieser Plug-ins durch uns erfolgt im Wege der sogenannten Zwei-Klick-Methode um Besucher unserer Webseite bestm\u00f6glich zu sch\u00fctzen.<\/p>\n<p>a) LinkedIn<\/p>\n<p>Auf unserer Website werden auch sogenannte Social Plugins (\u201ePlugins\u201c) von LinkedIn Ireland Unlimited Company, Wilton Place, Dublin 2, Irland; betrieben.<\/p>\n<p>Die Plugins sind mit einem LinkedIn-Logo beispielsweise in Form der Buchstaben \u201eIN\u201c in wei\u00dfer Schrift gekennzeichnet.<\/p>\n<p>Wenn Sie eine Seite unseres Webauftritts aufrufen, die ein solches Plugin enth\u00e4lt, stellt Ihr Browser eine direkte Verbindung zu den Servern von LinkedIn her. Der Inhalt des Plugins wird von LinkedIn direkt an Ihren Browser \u00fcbermittelt und in die Seite eingebunden. Durch diese Einbindung erh\u00e4lt LinkedIn die Information, dass Ihr Browser die entsprechende Seite unseres Webauftritts aufgerufen hat, auch wenn Sie kein LinkedIn-Profil besitzen oder gerade nicht bei LinkedIn eingeloggt sind.<\/p>\n<p>Diese Information (einschlie\u00dflich Ihrer IP-Adresse) wird von Ihrem Browser direkt an einen Server von LinkedIn \u00fcbermittelt und dort gespeichert. Sind Sie bei LinkedIn eingeloggt, kann LinkedIn den Besuch unserer Website Ihrem LinkedIn-Account unmittelbar zuordnen. Wenn Sie mit den Plugins interagieren, zum Beispiel den \u201eLinkedIn\u201c-Button bet\u00e4tigen, wird diese Information ebenfalls direkt an einen Server von LinkedIn \u00fcbermittelt und dort gespeichert.<\/p>\n<p>Die Informationen werden au\u00dferdem auf Ihrem LinkedIn-Account ver\u00f6ffentlicht und dort Ihren Kontakten angezeigt.<\/p>\n<p>Wenn Sie nicht m\u00f6chten, dass LinkedIn die \u00fcber unseren Webauftritt gesammelten Daten unmittelbar Ihrem LinkedIn-Account zuordnet, m\u00fcssen Sie sich vor Ihrem Besuch unserer Website bei LinkedIn ausloggen.<\/p>\n<p>Weitere Informationen hierzu erhalten Sie in der Datenschutzerkl\u00e4rung<span style=\"font-size: 17px; letter-spacing: 0px;\"> von LinkedIn:\u00a0<\/span><a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener\"><span style=\"background-color: #ffffff; font-size: 17px; letter-spacing: 0px;\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/span><\/a><\/p>\n<p>\u00a0<\/p>\n<p>b) Xing<\/p>\n<p>Auf unserer Website werden auch sogenannte Social Plugins (\u201ePlugins\u201c) von Xing betrieben, Anbieter ist die New Work SE, Dammtorstra\u00dfe 30,20354 Hamburg, Deutschland.<\/p>\n<p>Die Plugins sind mit einem Xing-Logo beispielsweise in Form des Buchstabens \u201eX\u201c in gr\u00fcner Schrift gekennzeichnet.<\/p>\n<p>Wenn Sie eine Seite unseres Webauftritts aufrufen, die ein solches Plugin enth\u00e4lt, stellt Ihr Browser eine direkte Verbindung zu den Servern von Xing her. Der Inhalt des Plugins wird von Xing direkt an Ihren Browser \u00fcbermittelt und in die Seite eingebunden. Durch diese Einbindung erh\u00e4lt Xing die Information, dass Ihr Browser die entsprechende Seite unseres Webauftritts aufgerufen hat, auch wenn Sie kein Xing-Profil besitzen oder gerade nicht bei Xing eingeloggt sind.<\/p>\n<p>Diese Information (einschlie\u00dflich Ihrer IP-Adresse) wird von Ihrem Browser direkt an einen Server von Xing \u00fcbermittelt und dort gespeichert. Sind Sie bei Xing eingeloggt, kann Xing den Besuch unserer Website Ihrem Xing-Account unmittelbar zuordnen. Wenn Sie mit den Plugins interagieren, zum Beispiel den \u201eXing\u201c-Button bet\u00e4tigen, wird diese Information ebenfalls direkt an einen Server von Xing \u00fcbermittelt und dort gespeichert.<\/p>\n<p>Die Informationen k\u00f6nnen au\u00dferdem auf Ihrem Xing-Account ver\u00f6ffentlicht und dort Ihren Kontakten angezeigt werden.<\/p>\n<p>Wenn Sie nicht m\u00f6chten, dass Xing die \u00fcber unseren Webauftritt gesammelten Daten unmittelbar Ihrem Xing-Account zuordnet, m\u00fcssen Sie sich vor Ihrem Besuch unserer Website bei Xing ausloggen.<\/p>\n<p>Weitere Informationen hierzu erhalten Sie in der Datenschutzerkl\u00e4rung von Xing:\u00a0<a href=\"https:\/\/privacy.xing.com\/de\/datenschutzerklaerung\" target=\"_blank\" rel=\"noopener\"><span style=\"font-size: 17px; letter-spacing: 0px; background-color: #ffffff;\">h<\/span><span style=\"font-size: 17px; letter-spacing: 0px; background-color: #ffffff;\">ttps:\/\/privacy.xing.com\/de\/datenschutzerklaerung<\/span><\/a><\/p>\n<p>Wenn Sie nicht m\u00f6chten, dass soziale Netzwerke Daten \u00fcber Sie erh\u00e4lt, d\u00fcrfen Sie die entsprechenden Buttons nicht anklicken.<\/p>\n<p>Sie k\u00f6nnen Ihre Cookie Einstellungen jederzeit \u00e4ndern, indem Sie auf den Kreis unten links auf dem Bildschirm klicken. Es \u00f6ffnen sich die Cookie Einstellungen.<\/p>\n<p>\u00a0<\/p>\n<p><strong>7. Friendly-Captcha (Bot-\/Spam-Schutz)<\/strong><\/p>\n<p>Unsere Webseite nutzt den Dienst Friendly Captcha<\/p>\n<p>Dieser Dienst ist ein Angebot der Friendly Captcha GmbH, Am Anger 3-5, 82237 W\u00f6rthsee, Deutschland.<\/p>\n<p>Friendly Captcha ist eine Schutzl\u00f6sung, um die Nutzung unserer Webseite durch automatisierte Programme \/ Skripte (sogenannte \u201eBots) zu erschweren.<\/p>\n<p>Wir haben hierzu in unsere Webseite f\u00fcr Kontaktformulare Programmcode von Friendly Captcha integriert, damit das Endger\u00e4t des Besuchers eine Verbindung zu den Servern von Friendly Captcha aufbauen kann, um von Friendly Captcha eine Rechenaufgabe zu erhalten. Das Endger\u00e4t des Besuchers l\u00f6st die Rechenaufgabe, wodurch gewisse Systemressourcen in Anspruch genommen werden, und schickt das Rechenergebnis an unseren Webserver. Dieser nimmt \u00fcber eine Schnittstelle Kontakt zum Server von Friendly Captcha auf und erh\u00e4lt als Antwort, ob das Puzzle vom Endger\u00e4t richtig gel\u00f6st wurde. Abh\u00e4ngig vom Ergebnis k\u00f6nnen wir Anfragen \u00fcber unsere Webseite mit Sicherheitsregeln versehen und sie so beispielsweise weiterbearbeiten oder ablehnen.<\/p>\n<p>Die Daten werden ausschlie\u00dflich zum oben beschriebenen Schutz vor Spam und Bots verwendet. Durch Friendly Captcha werden keine Cookies auf dem Endger\u00e4t des Besuchers gesetzt oder ausgelesen. IP-Adressen werden nur in gehashter, also einwegverschl\u00fcsselter Form gespeichert und erlauben uns und Friendly Captcha keinen R\u00fcckschluss auf eine Einzelperson. Wenn personenbezogene Daten gespeichert werden, werden diese Daten binnen 30 Tagen gel\u00f6scht. Rechtsgrundlage f\u00fcr die Verarbeitung sind unsere berechtigten Interessen am Schutz unserer Webseite vor missbr\u00e4uchlichen Zugriff durch Bots, mithin dem Spam-Schutz und dem Schutz vor Angriffen wie Massenanfragen, Artikel 6 Absatz 1 lit. f (DS-GVO)<\/p>\n<p>Weitere Informationen zum Datenschutz beim Einsatz von Friendly Captcha: <a href=\"https:\/\/friendlycaptcha.com\/de\/legal\/privacy-end-users\/\" target=\"_blank\" rel=\"noopener\">https:\/\/friendlycaptcha.com\/de\/legal\/privacy-end-users\/<\/a>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><strong>8. Betroffenenrechte<\/strong><\/p>\n<p>Sie haben das Recht:<\/p>\n<p>gem\u00e4\u00df Art. 15 DSGVO Auskunft \u00fcber Ihre von uns verarbeiteten personenbezogenen Daten zu verlangen. Insbesondere k\u00f6nnen Sie Auskunft \u00fcber die Verarbeitungszwecke, die Kategorie der personenbezogenen Daten, die Kategorien von Empf\u00e4ngern, gegen\u00fcber denen Ihre Daten offengelegt wurden oder werden, die geplante Speicherdauer, das Bestehen eines Rechts auf Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung oder Widerspruch, das Bestehen eines Beschwerderechts, die Herkunft ihrer Daten, sofern diese nicht bei uns erhoben wurden, sowie \u00fcber das Bestehen einer automatisierten Entscheidungsfindung einschlie\u00dflich Profiling und ggf. aussagekr\u00e4ftigen Informationen zu deren Einzelheiten verlangen;<\/p>\n<p>gem\u00e4\u00df Art. 16 DSGVO unverz\u00fcglich die Berichtigung unrichtiger oder Vervollst\u00e4ndigung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen;<\/p>\n<p>gem\u00e4\u00df Art. 17 DSGVO die L\u00f6schung Ihrer bei uns gespeicherten personenbezogenen Daten zu verlangen, soweit nicht die Verarbeitung zur Aus\u00fcbung des Rechts auf freie Meinungs\u00e4u\u00dferung und Information, zur Erf\u00fcllung einer rechtlichen Verpflichtung, aus Gr\u00fcnden des \u00f6ffentlichen Interesses oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen erforderlich ist;<\/p>\n<p>gem\u00e4\u00df Art. 18 DSGVO die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen, soweit die Richtigkeit der Daten von Ihnen bestritten wird, die Verarbeitung unrechtm\u00e4\u00dfig ist, Sie aber deren L\u00f6schung ablehnen und wir die Daten nicht mehr ben\u00f6tigen, Sie jedoch diese zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen ben\u00f6tigen oder Sie gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung eingelegt haben;<\/p>\n<p>gem\u00e4\u00df Art. 20 DSGVO Ihre personenbezogenen Daten, die Sie uns bereitgestellt haben, in einem strukturierten, g\u00e4ngigen und maschinenlesebaren Format zu erhalten oder die \u00dcbermittlung an einen anderen Verantwortlichen zu verlangen;<\/p>\n<p>gem\u00e4\u00df Art. 7 Abs. 3 DSGVO Ihre einmal erteilte Einwilligung jederzeit gegen\u00fcber uns zu widerrufen. Dies hat zur Folge, dass wir die Datenverarbeitung, die auf dieser Einwilligung beruhte, f\u00fcr die Zukunft nicht mehr fortf\u00fchren d\u00fcrfen und<\/p>\n<p>gem\u00e4\u00df Art. 77 DSGVO sich bei einer Aufsichtsbeh\u00f6rde zu beschweren. In der Regel k\u00f6nnen Sie sich hierf\u00fcr an die Aufsichtsbeh\u00f6rde Ihres \u00fcblichen Aufenthaltsortes oder Arbeitsplatzes oder unseres Kanzleisitzes wenden.<\/p>\n<p>\u00a0<\/p>\n<p><strong>9. Widerspruchsrecht<\/strong><\/p>\n<p>Sofern Ihre personenbezogenen Daten auf Grundlage von berechtigten Interessen gem\u00e4\u00df Art. 6 Abs. 1 S. 1 lit. f DSGVO verarbeitet werden, haben Sie das Recht, gem\u00e4\u00df Art. 21 DSGVO Widerspruch gegen die Verarbeitung Ihrer personenbezogenen Daten einzulegen, soweit daf\u00fcr Gr\u00fcnde vorliegen, die sich aus Ihrer besonderen Situation ergeben oder sich der Widerspruch gegen Direktwerbung richtet. Im letzteren Fall haben Sie ein generelles Widerspruchsrecht, das ohne Angabe einer besonderen Situation von uns umgesetzt wird.<\/p>\n<p>M\u00f6chten Sie von Ihrem Widerrufs- oder Widerspruchsrecht Gebrauch machen, gen\u00fcgt eine E-Mail an <a href=\"data@sternchemie.de\" target=\"_blank\" rel=\"noopener\">data@sternchemie.de<\/a>.<\/p>\n<p>\u00a0<\/p>\n<p><strong>10. Datensicherheit<\/strong><\/p>\n<p>Wir verwenden innerhalb des Website-Besuchs das verbreitete SSL-Verfahren (Secure Socket Layer) in Verbindung mit der jeweils h\u00f6chsten Verschl\u00fcsselungsstufe, die von Ihrem Browser unterst\u00fctzt wird. In der Regel handelt es sich dabei um eine 256 Bit Verschl\u00fcsselung. Falls Ihr Browser keine 256-Bit Verschl\u00fcsselung unterst\u00fctzt, greifen wir stattdessen auf 128-Bit v3 Technologie zur\u00fcck. Ob eine einzelne Seite unseres Internetauftrittes verschl\u00fcsselt \u00fcbertragen wird, erkennen Sie an der geschlossenen Darstellung des Sch\u00fcssel- beziehungsweise Schloss-Symbols in der unteren Statusleiste Ihres Browsers.<\/p>\n<p>Wir bedienen uns im \u00dcbrigen geeigneter technischer und organisatorischer Sicherheitsma\u00dfnahmen, um Ihre Daten gegen zuf\u00e4llige oder vors\u00e4tzliche Manipulationen, teilweisen oder vollst\u00e4ndigen Verlust, Zerst\u00f6rung oder gegen den unbefugten Zugriff Dritter zu sch\u00fctzen. Unsere Sicherheitsma\u00dfnahmen werden entsprechend der technologischen Entwicklung fortlaufend verbessert.<\/p>\n<p>\u00a0<\/p>\n<p><strong>11. Links zu Websites Dritter<\/strong><\/p>\n<p>Unsere Website kann gegebenenfalls Links zu Websites von anderen Plattformen, Partnern und Dienstleistern enthalten, auf die sich diese Datenschutzerkl\u00e4rung nicht erstreckt. Wenn Sie eine Website dieser Dritten aufsuchen, gelten entsprechend dessen Datenschutzhinweise und Nutzungsbedingungen. Eine Haftung f\u00fcr fremde Webseiten wird hiermit ausgeschlossen.<\/p>\n<p>\u00a0<\/p>\n<p><strong>12. Aktualit\u00e4t und \u00c4nderung dieser Datenschutzerkl\u00e4rung<\/strong><\/p>\n<p>Diese Datenschutzerkl\u00e4rung ist aktuell g\u00fcltig und hat den Stand Juli 2024.<\/p>\n<p>Durch die Weiterentwicklung unserer Website und Angebote dar\u00fcber oder aufgrund ge\u00e4nderter gesetzlicher beziehungsweise beh\u00f6rdlicher Vorgaben kann es notwendig werden, diese Datenschutzerkl\u00e4rung zu \u00e4ndern. Die jeweils aktuelle Datenschutzerkl\u00e4rung kann jederzeit auf der Website unter <a href=\"https:\/\/www.sternchemie.com\/de\/datenschutz\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sternchemie.com\/de\/datenschutz<\/a>\u00a0von Ihnen abgerufen und ausgedruckt werden.\u00a0<\/p>\n<\/div><\/div><\/div><\/div><div class = \"tatsu-column-bg-image-wrap\"><div class = \"tatsu-column-bg-image tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-column-overlay tatsu-animate-none\" ><\/div><\/div><style>.tatsu-row > .tatsu-gg9fxvdr0t9rudhd.tatsu-column{width: 100%;}.tatsu-gg9fxvdr0t9rudhd.tatsu-column > .tatsu-column-inner > .tatsu-column-overlay{mix-blend-mode: normal;}.tatsu-gg9fxvdr0t9rudhd > .tatsu-column-inner > .tatsu-top-divider{z-index: 9999;}.tatsu-gg9fxvdr0t9rudhd > .tatsu-column-inner > .tatsu-bottom-divider{z-index: 9999;}.tatsu-gg9fxvdr0t9rudhd > .tatsu-column-inner > .tatsu-left-divider{z-index: 9999;}.tatsu-gg9fxvdr0t9rudhd > .tatsu-column-inner > .tatsu-right-divider{z-index: 9999;}<\/style><\/div><\/div><\/div><\/div><div class=\"tatsu-section-background-wrap\"><div class = \"tatsu-section-background tatsu-bg-lazyload\" data-src = \"\"><\/div><\/div><div class=\"tatsu-overlay tatsu-section-overlay\"><\/div><style>.tatsu-gg9fxvdqw0fk6qd1 .tatsu-section-pad{padding: 90px 0px 90px 0px;}.tatsu-gg9fxvdqw0fk6qd1 > .tatsu-bottom-divider{z-index: 9999;}.tatsu-gg9fxvdqw0fk6qd1 > .tatsu-top-divider{z-index: 9999;}.tatsu-gg9fxvdqw0fk6qd1 .tatsu-section-overlay{mix-blend-mode: normal;}<\/style><\/div>\n","protected":false},"excerpt":{"rendered":"<div><a href=\"https:\/\/www.sternchemie.com\/de\/datenschutz\/\" class=\"exp-read-more exp-read-more-underlined\">Weiterlesen<\/a><\/div>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"categories":[99],"tags":[],"class_list":["post-3","page","type-page","status-publish","hentry","category-ausschliessen-in-der-internen-suche"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie<\/title>\n<meta name=\"description\" content=\"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH &amp; Co. KG.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sternchemie.com\/de\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie\" \/>\n<meta property=\"og:description\" content=\"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH &amp; Co. KG.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sternchemie.com\/de\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"Sternchemie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/category\/Industrial-Company\/Sternchemie-1634859096597137\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T14:18:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"21\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/datenschutz\\\/\",\"name\":\"Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#website\"},\"datePublished\":\"2019-09-20T08:48:01+00:00\",\"dateModified\":\"2026-03-30T14:18:39+00:00\",\"description\":\"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH & Co. KG.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/datenschutz\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/\",\"name\":\"Sternchemie\",\"description\":\"Anwendungsorientierte, moderne Lecithin- und Lipidl\u00f6sungen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#organization\",\"name\":\"Sternchemie GmbH & Co. KG\",\"url\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sternchemie.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Sternchemie_Logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.sternchemie.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Sternchemie_Logo.svg\",\"width\":183,\"height\":53,\"caption\":\"Sternchemie GmbH & Co. KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sternchemie.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/category\\\/Industrial-Company\\\/Sternchemie-1634859096597137\\\/\",\"https:\\\/\\\/de.linkedin.com\\\/company\\\/sternchemie\",\"https:\\\/\\\/de.wikipedia.org\\\/wiki\\\/Stern-Wywiol_Gruppe\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie","description":"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH & Co. KG.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sternchemie.com\/de\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie","og_description":"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH & Co. KG.","og_url":"https:\/\/www.sternchemie.com\/de\/datenschutz\/","og_site_name":"Sternchemie","article_publisher":"https:\/\/www.facebook.com\/pages\/category\/Industrial-Company\/Sternchemie-1634859096597137\/","article_modified_time":"2026-03-30T14:18:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"21\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sternchemie.com\/de\/datenschutz\/","url":"https:\/\/www.sternchemie.com\/de\/datenschutz\/","name":"Datenschutz: Datenschutzerkl\u00e4rung - Sternchemie","isPartOf":{"@id":"https:\/\/www.sternchemie.com\/de\/#website"},"datePublished":"2019-09-20T08:48:01+00:00","dateModified":"2026-03-30T14:18:39+00:00","description":"Datenschutz: Datenschutzerkl\u00e4rung der Sternchemie GmbH & Co. KG.","breadcrumb":{"@id":"https:\/\/www.sternchemie.com\/de\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sternchemie.com\/de\/datenschutz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sternchemie.com\/de\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sternchemie.com\/de\/"},{"@type":"ListItem","position":2,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.sternchemie.com\/de\/#website","url":"https:\/\/www.sternchemie.com\/de\/","name":"Sternchemie","description":"Anwendungsorientierte, moderne Lecithin- und Lipidl\u00f6sungen","publisher":{"@id":"https:\/\/www.sternchemie.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sternchemie.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sternchemie.com\/de\/#organization","name":"Sternchemie GmbH & Co. KG","url":"https:\/\/www.sternchemie.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sternchemie.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.sternchemie.com\/wp-content\/uploads\/2020\/10\/Sternchemie_Logo.svg","contentUrl":"https:\/\/www.sternchemie.com\/wp-content\/uploads\/2020\/10\/Sternchemie_Logo.svg","width":183,"height":53,"caption":"Sternchemie GmbH & Co. KG"},"image":{"@id":"https:\/\/www.sternchemie.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/category\/Industrial-Company\/Sternchemie-1634859096597137\/","https:\/\/de.linkedin.com\/company\/sternchemie","https:\/\/de.wikipedia.org\/wiki\/Stern-Wywiol_Gruppe"]}]}},"_links":{"self":[{"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":42,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":11845,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions\/11845"}],"wp:attachment":[{"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/media?parent=3"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/categories?post=3"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sternchemie.com\/de\/wp-json\/wp\/v2\/tags?post=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}